{"id":846,"date":"2022-05-28T09:41:24","date_gmt":"2022-05-28T06:41:24","guid":{"rendered":"https:\/\/mussangroup.com\/fr\/?p=846"},"modified":"2022-05-28T09:41:26","modified_gmt":"2022-05-28T06:41:26","slug":"que-sont-les-elements-de-moulage-par-injection-plastique","status":"publish","type":"post","link":"https:\/\/mussangroup.com\/fr\/que-sont-les-elements-de-moulage-par-injection-plastique\/","title":{"rendered":"Que sont les \u00e9l\u00e9ments de moulage par injection plastique ?"},"content":{"rendered":"\n<p><strong>Que sont les \u00e9l\u00e9ments de moulage par injection plastique ?<\/strong><\/p>\n\n\n\n<p>Ce sont des \u00e9l\u00e9ments de moulage par injection plastique, c&#8217;est-\u00e0-dire des accessoires de moulage. Il existe de nombreux accessoires dans le moule d&#8217;injection plastique, c&#8217;est-\u00e0-dire qu&#8217;il y a environ 300 pages d&#8217;accessoires de moule dans un catalogue moyen, y compris des citations de nombreuses sources. Cependant, il nous est impossible de tous les conna\u00eetre et de les utiliser tous dans un m\u00eame sch\u00e9ma. Nos \u00e9l\u00e9ments de moule indispensables dans une injection plastique. Tout d&#8217;abord, ce sont les mat\u00e9riaux que nous appelons la colonne et la douille, qui sont utilis\u00e9s dans le centrage du moule. Ce sont les mat\u00e9riaux qui permettent de d\u00e9mouler la mati\u00e8re plastique, que l&#8217;on appelle le poussoir, qui refroidit dans le moule et prend la forme du moule. Un autre est la buse d&#8217;injection plastique, qui est fabriqu\u00e9e \u00e0 partir de la machine d&#8217;injection plastique au point d&#8217;entr\u00e9e dans le premier moule du plastique, sous forme conique invers\u00e9e, et il existe des mat\u00e9riaux que nous appelons la buse d&#8217;injection plastique, qui sont broy\u00e9s et trait\u00e9s thermiquement de sorte que la chaleur du plastique n&#8217;use pas rapidement le mat\u00e9riau. \u00c9tant donn\u00e9 que ces mat\u00e9riaux sont \u00e9galement s\u00e9par\u00e9s en eux-m\u00eames, par exemple, les colonnes sont diverses, telles que les chapeaux \u00e0 queue, etc. Les broches d&#8217;\u00e9jection ont de nombreuses variantes telles que la t\u00eate frais\u00e9e \u00e0 t\u00eate plate, etc. Ces mat\u00e9riaux sont s\u00e9lectionn\u00e9s en fonction de leur place et de leur forme par nos artisans exp\u00e9riment\u00e9s, et ils sont assembl\u00e9s dans les moules d&#8217;injection plastique que nous produisons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que sont les \u00e9l\u00e9ments de moulage par injection plastique ? Ce sont des \u00e9l\u00e9ments de moulage par injection plastique, c&#8217;est-\u00e0-dire des accessoires de moulage. Il existe de nombreux accessoires dans le moule d&#8217;injection plastique, c&#8217;est-\u00e0-dire qu&#8217;il y a environ 300 pages d&#8217;accessoires de moule dans un catalogue moyen, y compris des citations de nombreuses sources. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[66],"tags":[273],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/posts\/846"}],"collection":[{"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/comments?post=846"}],"version-history":[{"count":1,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/posts\/846\/revisions"}],"predecessor-version":[{"id":848,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/posts\/846\/revisions\/848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/media\/847"}],"wp:attachment":[{"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/media?parent=846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/categories?post=846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mussangroup.com\/fr\/wp-json\/wp\/v2\/tags?post=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}